{"id":10834,"date":"2025-12-22T08:40:52","date_gmt":"2025-12-22T07:40:52","guid":{"rendered":"https:\/\/bd-chroniques.be\/?p=10834"},"modified":"2025-12-22T17:50:17","modified_gmt":"2025-12-22T16:50:17","slug":"le-grizzli-du-polar-a-la-francaise-rejouissant","status":"publish","type":"post","link":"https:\/\/bd-chroniques.be\/index.php\/2025\/12\/22\/le-grizzli-du-polar-a-la-francaise-rejouissant\/","title":{"rendered":"Le Grizzli \u2013 Du polar \u00e0 la fran\u00e7aise, r\u00e9jouissant\u00a0!"},"content":{"rendered":"\n<p>Entrons de plain-pied, si vous le voulez bien, dans de la bande dessin\u00e9e qui se savoure comme du Lautner, comme de l\u2019Audiard&nbsp;! <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1019\" src=\"https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-27.png?resize=768%2C1019&#038;ssl=1\" alt=\"\" class=\"wp-image-10836\" srcset=\"https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-27.png?resize=772%2C1024&amp;ssl=1 772w, https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-27.png?resize=226%2C300&amp;ssl=1 226w, https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-27.png?resize=768%2C1019&amp;ssl=1 768w, https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-27.png?w=850&amp;ssl=1 850w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">copyright dargaud<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Matz et Fred Simon nous emm\u00e8nent en effet dans un univers tr\u00e8s \u00ab&nbsp;sixties&nbsp;\u00bb, avec un \u00ab&nbsp;h\u00e9ros&nbsp;\u00bb bien baraqu\u00e9, avec des personnages, d\u2019ailleurs, typiques de ces policiers, au cinoche comme en litt\u00e9rature dite de gare, qui sont pleins de verve et pleins aussi de bons gnons \u00e0 distribuer&nbsp;! Des personnages au travers desquels on peut sans peine voir des filiations avec pas mal de h\u00e9ros de l\u2019immense Audiard, en effet&nbsp;!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"225\" src=\"https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-28.png?resize=400%2C225&#038;ssl=1\" alt=\"\" class=\"wp-image-10837\" srcset=\"https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-28.png?w=400&amp;ssl=1 400w, https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-28.png?resize=300%2C169&amp;ssl=1 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption class=\"wp-element-caption\">copyright dargaud<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Lino Ventura, par exemple\u2026 Mais aussi ce qui faisait le plaisir de ce cin\u00e9ma-l\u00e0, des seconds r\u00f4les en veux-tu en voil\u00e0, caricatur\u00e9s certes, mais merveilleusement vivants, et donc \u00ab&nbsp;gouaillants&nbsp;\u00bb&nbsp;! Et le sc\u00e9nario de ces deux albums d\u00e9j\u00e0 parus, d\u2019ailleurs, ne cache pas son hommage \u00e0 ce style policier quelque peu d\u00e9suet mais passionnant, celui de Lautner entre autres, dans lequel l&rsquo;observation comme l&rsquo;humour sont sans cesse pr\u00e9sents! <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1013\" src=\"https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-29.png?resize=768%2C1013&#038;ssl=1\" alt=\"\" class=\"wp-image-10838\" srcset=\"https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-29.png?resize=776%2C1024&amp;ssl=1 776w, https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-29.png?resize=227%2C300&amp;ssl=1 227w, https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-29.png?resize=768%2C1014&amp;ssl=1 768w, https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-29.png?w=800&amp;ssl=1 800w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">copyright dargaud<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Le Grizzli, c\u2019est un ancien boxeur, un ancien truand aussi, rang\u00e9 des voitures. Dans le premier volume de ses aventures, \u00ab&nbsp;Un dr\u00f4le de chabanais&nbsp;\u00bb, il va reprendre du service pour aider un de ses potes restaurateur, Jo, en butte aux m\u00e9chancet\u00e9s d\u2019un sorti du placard, B\u00e9bert la Gambille&nbsp;! Dans le deuxi\u00e8me album paru, \u00ab&nbsp;une haleine de cadavre&nbsp;\u00bb, on se balade du c\u00f4t\u00e9 du cimeti\u00e8re de Montparnasse, on parle d\u2019enl\u00e8vement d\u2019une greluche et de l\u2019intervention muscl\u00e9e du Grizzli&nbsp;pour remettre toutes les pendules \u00e0 l\u2019heure, aux limites, bien entendu, de la l\u00e9galit\u00e9&nbsp;! Et sans jamais oublier les galipettes amoureuses!&#8230; <\/p>\n\n\n\n<p>Le tout est ponctu\u00e9 par des dialogues qui chantent bon la m\u00e9lodie d\u2019un \u00ab&nbsp;milieu&nbsp;\u00bb qui a sans doute bien disparu&nbsp;: \u00ab&nbsp;<em>Je suis pas s\u00fbr que le Christ, il pensait \u00e0 des gni\u00e8res avec des p\u00e9digr\u00e9s quand il disait qu\u2019il fallait pardonner \u00e0 son prochain.<\/em>&nbsp;\u00bb\u2026 Ou&nbsp;: \u00ab&nbsp;<em>B\u00e9bert La Gambille vient de sortit de taule, et \u00e7a ne me pla\u00eet pas du tout. Il est sorti sur un coup de vice que son baveux lui a d\u00e9gauchi.<\/em>&nbsp;\u00bb&nbsp;!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"712\" src=\"https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-30.png?resize=539%2C712&#038;ssl=1\" alt=\"\" class=\"wp-image-10839\" style=\"width:539px;height:auto\" srcset=\"https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-30.png?w=539&amp;ssl=1 539w, https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/image-30.png?resize=227%2C300&amp;ssl=1 227w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><figcaption class=\"wp-element-caption\">copyright dargaud<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Il ne faut jamais bouder son plaisir\u00a0! Et j\u2019ai pris plaisir, oui, \u00e0 lire ces deux bouquins, m\u00eame si, c\u2019est vrai, nul ne pourra jamais atteindre la perfection \u00ab\u00a0litt\u00e9raire\u00a0\u00bb d\u2019Audiard, et des immenses Blier, Gabin, Blanche, Ventura et compagnie\u00a0! Et je pense que ce Grizzli va nous faire vivre encore de nouvelles aventures\u00a0! En Bretagne, sans doute&#8230; Une s\u00e9rie \u00e0 savourer, avec un langage, en outre, qui fait l\u2019objet, en fins d\u2019albums, d\u2019un petit glossaire pas piqu\u00e9 des hannetons\u00a0!<\/p>\n\n\n\n<p><strong>Jacques et Josiane Schra\u00fbwen<\/strong><\/p>\n\n\n\n<p><strong>Le Grizzli- deux albums parus (dessin&nbsp;: Fred Simon \u2013 sc\u00e9nario&nbsp;: Matz \u2013 \u00e9diteur&nbsp;: Dargaud \u2013 2023 et 2025)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrons de plain-pied, si vous le voulez bien, dans de la bande dessin\u00e9e qui se savoure comme du Lautner, comme de l\u2019Audiard&nbsp;! Matz et Fred Simon nous emm\u00e8nent en effet dans un univers tr\u00e8s \u00ab&nbsp;sixties&nbsp;\u00bb, avec un \u00ab&nbsp;h\u00e9ros&nbsp;\u00bb bien baraqu\u00e9, avec des personnages, d\u2019ailleurs, typiques de ces policiers, au cinoche comme en litt\u00e9rature dite de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[22,30],"tags":[],"class_list":["post-10834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bd-de-g-a-l","category-g"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/bd-chroniques.be\/wp-content\/uploads\/2025\/12\/grizzli.jpg?fit=600%2C800&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8dqsu-2OK","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/posts\/10834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/comments?post=10834"}],"version-history":[{"count":2,"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/posts\/10834\/revisions"}],"predecessor-version":[{"id":10841,"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/posts\/10834\/revisions\/10841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/media\/10835"}],"wp:attachment":[{"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/media?parent=10834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/categories?post=10834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bd-chroniques.be\/index.php\/wp-json\/wp\/v2\/tags?post=10834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}